{"id":8230,"date":"2024-03-07T15:17:18","date_gmt":"2024-03-07T14:17:18","guid":{"rendered":"https:\/\/www.paguswinetours.com\/?page_id=8230"},"modified":"2025-01-16T12:40:08","modified_gmt":"2025-01-16T11:40:08","slug":"valpolicella-e-verona","status":"publish","type":"page","link":"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/","title":{"rendered":"Valpolicella e Verona"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8230\" class=\"elementor elementor-8230 elementor-8216\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-eb638ca elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb638ca\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0485812\" data-id=\"0485812\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-616f551 image-position-top elementor-widget elementor-widget-iqonic_title\" data-id=\"616f551\" data-element_type=\"widget\" data-widget_type=\"iqonic_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t<div class=\" text-left slainte-title-box slainte-title-box-2\">\n\t\t\t\t\t\t<div class=\"slainte-title-icon\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/icon_pagus_bianco_2.png\" title=\"\" alt=\"Pagus Wine Tours\" loading=\"lazy\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<h6 class=\"slainte-subtitle\">3 notti<\/h6>\t\t\t\t<h2 class=\"slainte-title slainte-heading-title\">\n\t\t\t<span class=\"right-text\">Valpolicella e<\/span>\n\t\t\t<span class=\"left-text-wrap wow\">\n\t\t\t\t<span class=\"left-text\">Verona<\/span>\n\t\t\t\t<span class=\"left-text-swipe\">Verona<\/span>\n\t\t\t<\/span>\n\n\t\t<\/h2>\n\n\t\t\t\t\n\t<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3fdd36 elementor-widget elementor-widget-text-editor\" data-id=\"d3fdd36\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un pacchetto dedicato alla scoperta di\u00a0<strong>Verona<\/strong>, della\u00a0<strong>Valpolicella<\/strong>\u00a0e dei suoi vini che include tre notti presso un\u00a0<strong>Agriturismo<\/strong>\u00a0sulle colline della Valpolicella Classica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-feef3c9 elementor-widget elementor-widget-iqonic_button\" data-id=\"feef3c9\" data-element_type=\"widget\" data-widget_type=\"iqonic_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"slainte-btn-container\">\n    <a class=\"slainte-button slainte-blog-link has-icon btn-icon-right\" href=\"#richiedi-informazioni\">\n        <span class=\"slainte-main-btn\">\n                        <span class=\"text-btn\">Richiedi informazioni<\/span>                            <span class=\"btn-icon\">\n                    <span class=\"btn-icon-inner\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"8\" viewBox=\"0 0 12 8\" fill=\"none\"><path d=\"M11.9267 3.82324L8.17673 0.0732513C8.10494 0.0019546 7.99826 -0.019772 7.90427 0.0190404C7.81076 0.0576184 7.74998 0.148931 7.74998 0.249993V0.749984C7.74998 0.816382 7.77635 0.879874 7.82323 0.926749L10.3965 3.49999H0.250007C0.11182 3.50001 0 3.61181 0 3.75V4.24999C0 4.38818 0.11182 4.5 0.250007 4.5H10.3965L7.82323 7.07324C7.77635 7.12011 7.74998 7.18358 7.74998 7.25V7.74999C7.74998 7.85108 7.81078 7.94237 7.90427 7.98095C7.93528 7.99388 7.96774 8 7.99997 8C8.06491 8 8.12887 7.97462 8.17673 7.92676L11.9267 4.17677C12.0244 4.07911 12.0244 3.9209 11.9267 3.82324Z\" fill=\"#70002A\"><\/path><\/svg>                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"8\" viewBox=\"0 0 12 8\" fill=\"none\"><path d=\"M11.9267 3.82324L8.17673 0.0732513C8.10494 0.0019546 7.99826 -0.019772 7.90427 0.0190404C7.81076 0.0576184 7.74998 0.148931 7.74998 0.249993V0.749984C7.74998 0.816382 7.77635 0.879874 7.82323 0.926749L10.3965 3.49999H0.250007C0.11182 3.50001 0 3.61181 0 3.75V4.24999C0 4.38818 0.11182 4.5 0.250007 4.5H10.3965L7.82323 7.07324C7.77635 7.12011 7.74998 7.18358 7.74998 7.25V7.74999C7.74998 7.85108 7.81078 7.94237 7.90427 7.98095C7.93528 7.99388 7.96774 8 7.99997 8C8.06491 8 8.12887 7.97462 8.17673 7.92676L11.9267 4.17677C12.0244 4.07911 12.0244 3.9209 11.9267 3.82324Z\" fill=\"#70002A\"><\/path><\/svg>                    <\/span>\n                <\/span>\n                    <\/span>\n    <\/a>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-12f0587\" data-id=\"12f0587\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c85a604 elementor-widget elementor-widget-image\" data-id=\"c85a604\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/vineyards-le-bignele-812x812-1.jpg\" class=\"attachment-full size-full wp-image-10191\" alt=\"Valpolicella and Verona\" srcset=\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/vineyards-le-bignele-812x812-1.jpg 800w, https:\/\/www.paguswinetours.com\/wp-content\/uploads\/vineyards-le-bignele-812x812-1-300x169.jpg 300w, https:\/\/www.paguswinetours.com\/wp-content\/uploads\/vineyards-le-bignele-812x812-1-768x432.jpg 768w, https:\/\/www.paguswinetours.com\/wp-content\/uploads\/vineyards-le-bignele-812x812-1-600x338.jpg 600w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-8ba1c87 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ba1c87\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f12f22\" data-id=\"4f12f22\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-772fe76 elementor-widget elementor-widget-iqonic_title\" data-id=\"772fe76\" data-element_type=\"widget\" data-widget_type=\"iqonic_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t<div class=\"center slainte-title-box slainte-title-box-2\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"slainte-title slainte-heading-title\">\n\t\t\t<span class=\"right-text\">Alcune<\/span>\n\t\t\t<span class=\"left-text-wrap wow\">\n\t\t\t\t<span class=\"left-text\">Foto<\/span>\n\t\t\t\t<span class=\"left-text-swipe\">Foto<\/span>\n\t\t\t<\/span>\n\n\t\t<\/h2>\n\n\t\t\t\t\n\t<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5aedf9 elementor-widget elementor-widget-iqonic_gallery\" data-id=\"f5aedf9\" data-element_type=\"widget\" data-widget_type=\"iqonic_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"slainte-gallery\">\n    <div class=\"iqonic-masonry-block iqonic-metro-block\">\n        <div class=\"iqonic-masonry-grid\">\n            <div class=\"grid-sizer\"><\/div>\n                            <div class=\"iqonic-masonry-item s-25 sqaure\">\n                    <a href=\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/ponte-pietra-di-notte-900x600-1.jpg\" data-fancybox=\"gallery\">\n                        <div class=\"gallery-overlay position-relative\">\n                            <img decoding=\"async\" src=\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/ponte-pietra-di-notte-900x600-1-325x230.jpg\" alt=\"image\" \/>\n                            <div class=\"view-image\">\n                                <svg width=\"16\" height=\"11\" viewBox=\"0 0 16 11\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                <path d=\"M15.8983 4.7877C15.7554 4.59216 12.3496 0 7.99992 0C3.65019 0 0.244313 4.59217 0.101531 4.78751C-0.0338438 4.97301 -0.0338438 5.2246 0.101531 5.4101C0.244313 5.60564 3.65019 10.1978 7.99992 10.1978C12.3496 10.1978 15.7554 5.60561 15.8983 5.41026C16.0339 5.22479 16.0339 4.97301 15.8983 4.7877ZM7.99992 9.14286C4.79588 9.14286 2.02085 6.09495 1.19938 5.09854C2.01979 4.10126 4.78901 1.05494 7.99992 1.05494C11.2038 1.05494 13.9787 4.10232 14.8005 5.09926C13.9801 6.09651 11.2108 9.14286 7.99992 9.14286Z\" fill=\"#D09D55\"\/>\n                                <path d=\"M7.99981 1.93408C6.25474 1.93408 4.83496 3.35387 4.83496 5.09893C4.83496 6.844 6.25474 8.26378 7.99981 8.26378C9.74487 8.26378 11.1647 6.844 11.1647 5.09893C11.1647 3.35387 9.74487 1.93408 7.99981 1.93408ZM7.99981 7.20881C6.83637 7.20881 5.88993 6.26234 5.88993 5.09893C5.88993 3.93552 6.8364 2.98905 7.99981 2.98905C9.16321 2.98905 10.1097 3.93552 10.1097 5.09893C10.1097 6.26234 9.16325 7.20881 7.99981 7.20881Z\" fill=\"#D09D55\"\/>\n                                <\/svg>\n                            <\/div>\n                        <\/div>\n                    <\/a>\n                <\/div>\n\n                            <div class=\"iqonic-masonry-item s-25 portrait\">\n                    <a href=\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/valpolicella-2.jpg\" data-fancybox=\"gallery\">\n                        <div class=\"gallery-overlay position-relative\">\n                            <img decoding=\"async\" src=\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/valpolicella-2-325x460.jpg\" alt=\"image\" \/>\n                            <div class=\"view-image\">\n                                <svg width=\"16\" height=\"11\" viewBox=\"0 0 16 11\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                <path d=\"M15.8983 4.7877C15.7554 4.59216 12.3496 0 7.99992 0C3.65019 0 0.244313 4.59217 0.101531 4.78751C-0.0338438 4.97301 -0.0338438 5.2246 0.101531 5.4101C0.244313 5.60564 3.65019 10.1978 7.99992 10.1978C12.3496 10.1978 15.7554 5.60561 15.8983 5.41026C16.0339 5.22479 16.0339 4.97301 15.8983 4.7877ZM7.99992 9.14286C4.79588 9.14286 2.02085 6.09495 1.19938 5.09854C2.01979 4.10126 4.78901 1.05494 7.99992 1.05494C11.2038 1.05494 13.9787 4.10232 14.8005 5.09926C13.9801 6.09651 11.2108 9.14286 7.99992 9.14286Z\" fill=\"#D09D55\"\/>\n                                <path d=\"M7.99981 1.93408C6.25474 1.93408 4.83496 3.35387 4.83496 5.09893C4.83496 6.844 6.25474 8.26378 7.99981 8.26378C9.74487 8.26378 11.1647 6.844 11.1647 5.09893C11.1647 3.35387 9.74487 1.93408 7.99981 1.93408ZM7.99981 7.20881C6.83637 7.20881 5.88993 6.26234 5.88993 5.09893C5.88993 3.93552 6.8364 2.98905 7.99981 2.98905C9.16321 2.98905 10.1097 3.93552 10.1097 5.09893C10.1097 6.26234 9.16325 7.20881 7.99981 7.20881Z\" fill=\"#D09D55\"\/>\n                                <\/svg>\n                            <\/div>\n                        <\/div>\n                    <\/a>\n                <\/div>\n\n                            <div class=\"iqonic-masonry-item s-25 sqaure\">\n                    <a href=\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/valpolicella.jpg\" data-fancybox=\"gallery\">\n                        <div class=\"gallery-overlay position-relative\">\n                            <img decoding=\"async\" src=\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/valpolicella-325x230.jpg\" alt=\"image\" \/>\n                            <div class=\"view-image\">\n                                <svg width=\"16\" height=\"11\" viewBox=\"0 0 16 11\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                <path d=\"M15.8983 4.7877C15.7554 4.59216 12.3496 0 7.99992 0C3.65019 0 0.244313 4.59217 0.101531 4.78751C-0.0338438 4.97301 -0.0338438 5.2246 0.101531 5.4101C0.244313 5.60564 3.65019 10.1978 7.99992 10.1978C12.3496 10.1978 15.7554 5.60561 15.8983 5.41026C16.0339 5.22479 16.0339 4.97301 15.8983 4.7877ZM7.99992 9.14286C4.79588 9.14286 2.02085 6.09495 1.19938 5.09854C2.01979 4.10126 4.78901 1.05494 7.99992 1.05494C11.2038 1.05494 13.9787 4.10232 14.8005 5.09926C13.9801 6.09651 11.2108 9.14286 7.99992 9.14286Z\" fill=\"#D09D55\"\/>\n                                <path d=\"M7.99981 1.93408C6.25474 1.93408 4.83496 3.35387 4.83496 5.09893C4.83496 6.844 6.25474 8.26378 7.99981 8.26378C9.74487 8.26378 11.1647 6.844 11.1647 5.09893C11.1647 3.35387 9.74487 1.93408 7.99981 1.93408ZM7.99981 7.20881C6.83637 7.20881 5.88993 6.26234 5.88993 5.09893C5.88993 3.93552 6.8364 2.98905 7.99981 2.98905C9.16321 2.98905 10.1097 3.93552 10.1097 5.09893C10.1097 6.26234 9.16325 7.20881 7.99981 7.20881Z\" fill=\"#D09D55\"\/>\n                                <\/svg>\n                            <\/div>\n                        <\/div>\n                    <\/a>\n                <\/div>\n\n                            <div class=\"iqonic-masonry-item s-25 portrait\">\n                    <a href=\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/valpolicella-3.jpg\" data-fancybox=\"gallery\">\n                        <div class=\"gallery-overlay position-relative\">\n                            <img decoding=\"async\" src=\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/valpolicella-3-325x460.jpg\" alt=\"image\" \/>\n                            <div class=\"view-image\">\n                                <svg width=\"16\" height=\"11\" viewBox=\"0 0 16 11\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                <path d=\"M15.8983 4.7877C15.7554 4.59216 12.3496 0 7.99992 0C3.65019 0 0.244313 4.59217 0.101531 4.78751C-0.0338438 4.97301 -0.0338438 5.2246 0.101531 5.4101C0.244313 5.60564 3.65019 10.1978 7.99992 10.1978C12.3496 10.1978 15.7554 5.60561 15.8983 5.41026C16.0339 5.22479 16.0339 4.97301 15.8983 4.7877ZM7.99992 9.14286C4.79588 9.14286 2.02085 6.09495 1.19938 5.09854C2.01979 4.10126 4.78901 1.05494 7.99992 1.05494C11.2038 1.05494 13.9787 4.10232 14.8005 5.09926C13.9801 6.09651 11.2108 9.14286 7.99992 9.14286Z\" fill=\"#D09D55\"\/>\n                                <path d=\"M7.99981 1.93408C6.25474 1.93408 4.83496 3.35387 4.83496 5.09893C4.83496 6.844 6.25474 8.26378 7.99981 8.26378C9.74487 8.26378 11.1647 6.844 11.1647 5.09893C11.1647 3.35387 9.74487 1.93408 7.99981 1.93408ZM7.99981 7.20881C6.83637 7.20881 5.88993 6.26234 5.88993 5.09893C5.88993 3.93552 6.8364 2.98905 7.99981 2.98905C9.16321 2.98905 10.1097 3.93552 10.1097 5.09893C10.1097 6.26234 9.16325 7.20881 7.99981 7.20881Z\" fill=\"#D09D55\"\/>\n                                <\/svg>\n                            <\/div>\n                        <\/div>\n                    <\/a>\n                <\/div>\n\n            \n        <\/div>\n    <\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-d8da66f elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8da66f\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0016967\" data-id=\"0016967\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3780e21 elementor-widget elementor-widget-text-editor\" data-id=\"3780e21\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"italic\">Dettagli<\/h3>\n<p><strong><u>Giorno 1<\/u><\/strong><\/p>\n<p>In mattinata arrivo presso l&#8217;Agriturismo, accoglienza e sistemazione degli ospiti ai quali verr\u00e0 servito un aperitivo di benvenuto e il programma del soggiorno.<br \/>Nel pomeriggio alle ore 14.00 incontro con la guida, pick up e partenza del\u00a0<strong>tour privato &#8220;Un assaggio di Valpolicella&#8221;\u00a0<\/strong>. Percorrendo la strada del vino della Valpolicella, che regala splendidi panorami sui vigneti, visiterete il villaggio di San Giorgio Ingannapoltron o il santuario di Santa Maria Valverde. Seguiranno visita e degustazione dei vini Doc e Docg accompagnata da tagliere presso una cantina.<br \/>Serata libera e pernottamento in agriturismo.<\/p>\n<p><strong><u>Giorno 2<\/u><\/strong><\/p>\n<p>Colazione presso l\u2019Agriturismo e alle ore 9.00 incontro con la guida, pick up e partenza del\u00a0<strong>tour privato<\/strong>\u00a0\u201cCibo e Vino in Valpolicella\u201d.<strong>\u00a0<\/strong>Percorrendo la strada del vino della\u00a0<strong>Valpolicella<\/strong>, che regala splendidi panorami sui vigneti, raggiungete il Parco Naturale della <strong>Lessinia, <\/strong>dove visiterete un\u00a0<strong>produttore<\/strong>\u00a0di<strong>\u00a0salumi e formaggi<\/strong> che vi proporr\u00e0 una degustazione dei migliori prodotti accompagnata da una bottiglia di vino. A seguire raggiungerete una <strong>trattoria\u00a0<\/strong>nel cuore della\u00a0<strong>Valpolicella\u00a0<\/strong>dove potrete godervi un delizioso <strong>pranzo<\/strong> tradizionale.\u00a0 Seguiranno visita e <strong>degustazione dei vini<\/strong>\u00a0Doc e Docg presso una cantina.<br \/>Alla fine del tour, rientro all\u2019Agriturismo, serata libera e pernottamento.<\/p>\n<p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-370c262\" data-id=\"370c262\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef51c3d elementor-widget elementor-widget-text-editor\" data-id=\"ef51c3d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"letter-spacing: var(--font-letter-spacing-body)\"><span style=\"font-weight: bolder\"><u>Giorno 3<\/u><\/span><\/p>\n<p style=\"letter-spacing: var(--font-letter-spacing-body)\">Colazione presso l\u2019Agriturismo.<br \/>Ritrovo a\u00a0<span style=\"font-weight: bolder\">Verona<\/span>\u00a0e incontro con una guida turistica autorizzata presso il\u00a0<span style=\"font-weight: bolder\">PaguStore<\/span><span data-contrast=\"auto\">. Alle 9.30 partenza per il\u00a0<span style=\"font-weight: bolder\">tour privato<\/span>\u00a0<span style=\"font-weight: bolder\">\u201c<\/span><\/span>Passeggia e gusta Verona\u201d<span data-contrast=\"auto\">, un percorso a piedi alla scoperta del cuore della citt\u00e0 di Romeo e Giulietta. Visiterete le piazze e le strade pi\u00f9 famose di Verona, come Piazza Bra, via Mazzini, Piazza delle Erbe, Piazza dei Signori, il balcone di Giulietta e molti altri posti meravigliosi. Durante la passeggiata la guida vi introdurr\u00e0 alla storia della citt\u00e0. Descriver\u00e0 chiese, palazzi, resti romani e monumenti che troverete lungo il percorso. Poi ritorneremo presso il Pagus Store dove degusteremo vini locali accompagnati dai prodotti del territorio.<br \/>Pomeriggio libero a Verona e cena in un&#8217;<span style=\"font-weight: bolder\">osteria\u00a0<\/span>tradizionale del centro.<br \/>Pernottamento in agriturismo.<\/span><\/p>\n<p style=\"letter-spacing: var(--font-letter-spacing-body)\"><span style=\"font-weight: bolder\"><u>Giorno 4<\/u><\/span><\/p>\n<p style=\"letter-spacing: var(--font-letter-spacing-body)\">Colazione presso l\u2019Agriturismo, check out e consegna della<span style=\"font-weight: bolder\">\u00a0Veronacard\u00a0<\/span>per la visita dei musei valida per la giornata.<\/p>\n<h3 class=\"italic\" style=\"font-weight: var(--font-weight-h3);line-height: var(--font-line-height-h3);font-size: var(--font-size-h3);font-family: var(--highlight-font-family);letter-spacing: var(--font-letter-spacing-h3)\">Incluso<\/h3>\n<p style=\"letter-spacing: var(--font-letter-spacing-body)\">&#8211; Tre notti in camera matrimoniale e colazione presso un Agriturismo nella Valpolicella Classica<br \/>&#8211; Due wine tour privati con trasporto in minivan<br \/>&#8211; Tour di Verona con guida autorizzata e Veronacard<br \/>&#8211; Tour leader\/sommelier a disposizione per tutta la durata dei tour<br \/>&#8211; Visite e degustazioni presso due cantine in Valpolicella e un wine shop a Verona (almeno tre vini accompagnati da pane, formaggio e\/o salumi)<br \/>&#8211; Degustazione di formaggi e salumi<br \/>&#8211; Pranzo (vino incluso) presso una trattoria in Valpolicella, cena presso osteria a Verona (vino incluso)<br \/>&#8211; Tour di Verona con guida autorizzata<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-7e1bc40 elementor-section-stretched elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e1bc40\" data-element_type=\"section\" id=\"richiedi-informazioni\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d46699\" data-id=\"0d46699\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-227b96a image-position-top elementor-widget elementor-widget-iqonic_title\" data-id=\"227b96a\" data-element_type=\"widget\" data-widget_type=\"iqonic_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t<div class=\" text-left slainte-title-box slainte-title-box-2\">\n\t\t\t\t\t\t<div class=\"slainte-title-icon\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/icon_pagus_bianco_2.png\" title=\"\" alt=\"Pagus Wine Tours\" loading=\"lazy\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<h6 class=\"slainte-subtitle\">contattaci<\/h6>\t\t\t\t<h2 class=\"slainte-title slainte-heading-title\">\n\t\t\t<span class=\"right-text\">Richiedi<\/span>\n\t\t\t<span class=\"left-text-wrap wow\">\n\t\t\t\t<span class=\"left-text\">informazioni<\/span>\n\t\t\t\t<span class=\"left-text-swipe\">informazioni<\/span>\n\t\t\t<\/span>\n\n\t\t<\/h2>\n\n\t\t\t\t\n\t<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c3a168 elementor-widget elementor-widget-shortcode\" data-id=\"6c3a168\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f7425-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"7425\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/8230#wpcf7-f7425-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"7425\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f7425-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.4\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-md-6 col-sm-12\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6 col-sm-12\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-surname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Cognome\" value=\"\" type=\"text\" name=\"your-surname\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-6 col-sm-12\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Indirizzo Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6 col-sm-12\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefono\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-6 col-sm-12\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-country\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Stato\" value=\"\" type=\"text\" name=\"your-country\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6 col-sm-12\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-people\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"N\u00b0 Persone\" value=\"\" type=\"number\" name=\"your-people\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-12 col-sm-12\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"message-49\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Messaggio\" name=\"message-49\"><\/textarea><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-12 col-sm-12\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-123\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-123\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Autorizzo il trattamento dei miei dati personali. <a href=\"\/it\/privacy-policy\" target=\"_blank\">Clicca qui per approfondire<\/a>.<\/span><\/label><\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-12 col-sm-12\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Invia\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"dynamic_post_title\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"dynamic_post_url\" \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>3 notti Valpolicella e Verona Verona Un pacchetto dedicato alla scoperta di\u00a0Verona, della\u00a0Valpolicella\u00a0e dei suoi vini che include tre notti presso un\u00a0Agriturismo\u00a0sulle colline della Valpolicella Classica. Richiedi informazioni Alcune Foto Foto Dettagli Giorno 1 In mattinata arrivo presso l&#8217;Agriturismo, accoglienza e sistemazione degli ospiti ai quali verr\u00e0 servito un aperitivo di benvenuto e il programma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10191,"parent":8204,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8230","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Valpolicella e Verona - Pagus Wine Tours<\/title>\n<meta name=\"description\" content=\"Un pacchetto di tre notti dedicato alla scoperta di Verona e della Valpolicella Classica e dei suoi vini pregiati.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valpolicella e Verona\" \/>\n<meta property=\"og:description\" content=\"Un pacchetto di tre notti dedicato alla scoperta di Verona e della Valpolicella Classica e dei suoi vini pregiati.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/\" \/>\n<meta property=\"og:site_name\" content=\"Pagus Wine Tours\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/paguswinetours\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-16T11:40:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/vineyards-le-bignele-812x812-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/\",\"url\":\"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/\",\"name\":\"Valpolicella e Verona - Pagus Wine Tours\",\"isPartOf\":{\"@id\":\"https:\/\/www.paguswinetours.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/vineyards-le-bignele-812x812-1.jpg\",\"datePublished\":\"2024-03-07T14:17:18+00:00\",\"dateModified\":\"2025-01-16T11:40:08+00:00\",\"description\":\"Un pacchetto di tre notti dedicato alla scoperta di Verona e della Valpolicella Classica e dei suoi vini pregiati.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/#primaryimage\",\"url\":\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/vineyards-le-bignele-812x812-1.jpg\",\"contentUrl\":\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/vineyards-le-bignele-812x812-1.jpg\",\"width\":800,\"height\":450,\"caption\":\"Valpolicella and Verona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.paguswinetours.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vacanze nelle terre del vino\",\"item\":\"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Valpolicella e Verona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.paguswinetours.com\/it\/#website\",\"url\":\"https:\/\/www.paguswinetours.com\/it\/\",\"name\":\"Pagus Wine Tours\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.paguswinetours.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.paguswinetours.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.paguswinetours.com\/it\/#organization\",\"name\":\"Pagus Wine Tours\",\"url\":\"https:\/\/www.paguswinetours.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.paguswinetours.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/logo-2-1.png\",\"contentUrl\":\"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/logo-2-1.png\",\"width\":1172,\"height\":364,\"caption\":\"Pagus Wine Tours\"},\"image\":{\"@id\":\"https:\/\/www.paguswinetours.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/paguswinetours\/\",\"https:\/\/www.instagram.com\/paguswinetours\/\",\"https:\/\/www.youtube.com\/channel\/UCMuOOU3pfYQT2zysLFm2u8g\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valpolicella e Verona - Pagus Wine Tours","description":"Un pacchetto di tre notti dedicato alla scoperta di Verona e della Valpolicella Classica e dei suoi vini pregiati.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/","og_locale":"it_IT","og_type":"article","og_title":"Valpolicella e Verona","og_description":"Un pacchetto di tre notti dedicato alla scoperta di Verona e della Valpolicella Classica e dei suoi vini pregiati.","og_url":"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/","og_site_name":"Pagus Wine Tours","article_publisher":"https:\/\/www.facebook.com\/paguswinetours\/","article_modified_time":"2025-01-16T11:40:08+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/vineyards-le-bignele-812x812-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/","url":"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/","name":"Valpolicella e Verona - Pagus Wine Tours","isPartOf":{"@id":"https:\/\/www.paguswinetours.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/#primaryimage"},"image":{"@id":"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/vineyards-le-bignele-812x812-1.jpg","datePublished":"2024-03-07T14:17:18+00:00","dateModified":"2025-01-16T11:40:08+00:00","description":"Un pacchetto di tre notti dedicato alla scoperta di Verona e della Valpolicella Classica e dei suoi vini pregiati.","breadcrumb":{"@id":"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/#primaryimage","url":"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/vineyards-le-bignele-812x812-1.jpg","contentUrl":"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/vineyards-le-bignele-812x812-1.jpg","width":800,"height":450,"caption":"Valpolicella and Verona"},{"@type":"BreadcrumbList","@id":"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/valpolicella-e-verona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.paguswinetours.com\/it\/"},{"@type":"ListItem","position":2,"name":"Vacanze nelle terre del vino","item":"https:\/\/www.paguswinetours.com\/it\/pacchetti-vacanza\/"},{"@type":"ListItem","position":3,"name":"Valpolicella e Verona"}]},{"@type":"WebSite","@id":"https:\/\/www.paguswinetours.com\/it\/#website","url":"https:\/\/www.paguswinetours.com\/it\/","name":"Pagus Wine Tours","description":"","publisher":{"@id":"https:\/\/www.paguswinetours.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.paguswinetours.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.paguswinetours.com\/it\/#organization","name":"Pagus Wine Tours","url":"https:\/\/www.paguswinetours.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.paguswinetours.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/logo-2-1.png","contentUrl":"https:\/\/www.paguswinetours.com\/wp-content\/uploads\/logo-2-1.png","width":1172,"height":364,"caption":"Pagus Wine Tours"},"image":{"@id":"https:\/\/www.paguswinetours.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/paguswinetours\/","https:\/\/www.instagram.com\/paguswinetours\/","https:\/\/www.youtube.com\/channel\/UCMuOOU3pfYQT2zysLFm2u8g"]}]}},"_links":{"self":[{"href":"https:\/\/www.paguswinetours.com\/it\/wp-json\/wp\/v2\/pages\/8230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.paguswinetours.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.paguswinetours.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.paguswinetours.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paguswinetours.com\/it\/wp-json\/wp\/v2\/comments?post=8230"}],"version-history":[{"count":16,"href":"https:\/\/www.paguswinetours.com\/it\/wp-json\/wp\/v2\/pages\/8230\/revisions"}],"predecessor-version":[{"id":11970,"href":"https:\/\/www.paguswinetours.com\/it\/wp-json\/wp\/v2\/pages\/8230\/revisions\/11970"}],"up":[{"embeddable":true,"href":"https:\/\/www.paguswinetours.com\/it\/wp-json\/wp\/v2\/pages\/8204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paguswinetours.com\/it\/wp-json\/wp\/v2\/media\/10191"}],"wp:attachment":[{"href":"https:\/\/www.paguswinetours.com\/it\/wp-json\/wp\/v2\/media?parent=8230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}